{"id":17,"date":"2020-09-12T11:39:37","date_gmt":"2020-09-12T11:39:37","guid":{"rendered":"http:\/\/ppc.demo.oyounmedia.com\/?page_id=17"},"modified":"2025-12-04T23:03:18","modified_gmt":"2025-12-04T23:03:18","slug":"home","status":"publish","type":"page","link":"https:\/\/unipalgt.com\/en\/","title":{"rendered":"Homepage"},"content":{"rendered":"\n  <div class=\"banner has-hover has-video\" id=\"banner-2028709823\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                        \t<div class=\"video-overlay no-click fill visible\"><\/div>\n\t<video class=\"video-bg fill visible\" preload playsinline autoplay muted loop>\n\t\t<source src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/Unipal-WebSite-Video-Palestine-2.mp4\" type=\"video\/mp4\">\t<\/video>\n                        \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2028709823 {\n  padding-top: 50%;\n}\n@media (min-width:550px) {\n  #banner-2028709823 {\n    padding-top: 40%;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover sticky-section hide-for-medium\" id=\"banner-1638626676\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1921\" height=\"737\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/75_new.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-943135699\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-2808158453\" class=\"text\">\n\t\t\n<h1 class=\"aos-item\"><span style=\"color: #034184;\">+<\/span><span style=\"color: #034184;\">20 World leading suppliers<\/span><\/h1>\n<h1 class=\"\"><span style=\"color: #034184;\">+<\/span><span style=\"color: #034184;\">80 Brands &amp; Counting<\/span><\/h1>\n<p><span style=\"color: #034184;\">We reach every household with a diverse basket of high-quality best value for money products<\/span><\/p>\n\t\t\n<style>\n#text-2808158453 {\n  font-size: 0.75rem;\n  line-height: 2;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/en\/\/our-brands\" class=\"button primary\"  >\n\t\t<span>Explore Brands<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-943135699 {\n  width: 72%;\n}\n#text-box-943135699 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n   <div id=\"text-box-1702531683\" class=\"text-box banner-layer x50 md-x50 lg-x50 y90 md-y90 lg-y90 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1702531683 {\n  width: 60%;\n}\n#text-box-1702531683 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n   <div id=\"text-box-1596773662\" class=\"text-box banner-layer x50 md-x50 lg-x50 y95 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<div class=\"slider-wrapper relative\" id=\"slider-1101747653\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-focus\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 1000,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": false,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.pmi.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/philip_morris.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.ooredoo.ps\/en\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/ooredoo2.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/ps.iqos.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/iqos.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 195.80310880829px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"Marlboro\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/Marlboro_Logo.svg-1.png\" title=\"Marlboro\" alt=\"Marlboro\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 130px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"Parliament\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/parliament-1-logo-png-transparent.png\" title=\"Parliament\" alt=\"Parliament\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 139.73630831643px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"L&amp;M\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/Lm_cigarettes_logo.png\" title=\"L&amp;M\" alt=\"L&amp;M\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 130.6993006993px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.facebook.com\/XLPalestine\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/XL_LOGO_new.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/us.pg.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/pg.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.ariel-info.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/arial.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/us.pg.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/tide.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 207.77777777778px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/us.pg.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/Lenor.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.facebook.com\/girlscan.palestine\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/always.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/pantene.com\/en-us\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/pantene.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.pampers.com\/en-us\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/pampers.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.headandshoulders.com\/en-us\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/head_shoulders.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.facebook.com\/TheFairyArabia\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/fairy.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.gillettearabia.com\/ar-sa\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/gillette2.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 349.42771084337px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.gillettearabia.com\/ar-sa\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/Gillette_Venus_logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.oralbarabia.com\/ar-sa\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/oralb.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.376px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/oldspice.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image__7_-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 210.1256684492px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/us.braun.com\/en-us\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image__8_-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.ferrero.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/ferrero.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.ferrerorocher.com\/int\/en\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/ferrero_rocher.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.nutella.com\/me\/ar\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/nutella.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.kinder.com\/me\/en\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/kinder.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.facebook.com\/RaffaelloMiddleEast\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/raffaello.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.08179419525px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.mars.com\/made-by-mars\/mars-wrigley\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/mars-wrigley.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.55555555556px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.orbitgum.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/Orbit-logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.376px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.marsbar.co.uk\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Mars_Logo_and_symbol__meaning__history__PNG__brand-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 172.91319857313px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.snickers.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/Snickers.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.55555555556px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/Bounty-logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 192.05649717514px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/Twix.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 298.21576763485px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/File_Galaxy_chocolate_brand_logo-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 203.88068181818px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/Jewels.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 164.56307692308px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/skittles-202446079.logowik.com_.webp\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 131px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/mms-vector.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.siniorafood.com\/en-us\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/siniora.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 232px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.facebook.com\/UNIPALGTC\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Screenshot_2025-11-10_at_16.22.41-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 131px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.reema.ps\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/REEMA-WEB-01.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.kelloggs.com\/en_US\/home.html\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/kelloggs.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.pringles.com\/us\/home.html\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/pringles.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 131px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.wkkellogg.com\/our-foods\/our-brands\/corn-flakes\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image-10.jpeg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 240.75722543353px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.kraftheinzcompany.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Screenshot_2025-11-16_at_14.42.13-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 130px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.lotusbiscoff.com\/en-us\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2023\/06\/download-10-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/americana.brightcreations.com\/who-we-are\/#:~:text=Americana%20Foods%3A,and%20cakes%2C%20chips%20and%20snacks.\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/americana.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.duracell.com\/en-us\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/duracell.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 131px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/nadec.com\/en\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2023\/03\/Nadec-logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.wella.com\/professional\/en-EN\/hair-color\/koleston-perfect\/koleston-perfect#\/?_k=2vr2ak\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/wella.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.scjohnson.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/scjohnson.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.raid.com\/en-us\/products\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/raid.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.pledge.com\/en-us\/products\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/Pledge.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.glade.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/glage.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.dior.com\/en_int\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/Dior.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.givenchy.com\/us\/en-US\/homepage\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/givenchy.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t\n<style>\n#slider-1101747653 .flickity-slider > * {\n  max-width: 0px!important;\n}\n<\/style>\n<\/div>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1596773662 {\n  width: 100%;\n}\n#text-box-1596773662 .text-box-content {\n  font-size: 98%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1638626676 {\n  padding-top: 402px;\n}\n#banner-1638626676 .banner-bg img {\n  object-position: 47% 47%;\n}\n@media (min-width:550px) {\n  #banner-1638626676 {\n    padding-top: 600px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover sticky-section hide-for-medium\" id=\"banner-1622327308\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/our_products.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1116024376\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h1><span style=\"font-size: 85%;\">Our products can be found in +8,000 POS +2,800 are directly covered<\/span><\/h1>\n<a href=\"\/en\/capabilities\" class=\"button white\"  >\n\t\t<span>Explore More<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1116024376 {\n  width: 72%;\n}\n#text-box-1116024376 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1622327308 {\n  padding-top: 377px;\n}\n#banner-1622327308 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n#banner-1622327308 .banner-bg img {\n  object-position: 43% 46%;\n}\n@media (min-width:550px) {\n  #banner-1622327308 {\n    padding-top: 600px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\n\n  <div class=\"banner has-hover sticky-section hide-for-medium\" id=\"banner-1311723773\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1794\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/DSC00350-scaled.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-694815492\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-1450175576\" class=\"text\">\n\t\t\n<h1>3 Distribution Centers<\/h1>\n<h2>Ramallah \/ East Jerusalem \/ Gaza*<\/h2>\n<h1>+15,500 Pallets Capacity<\/h1>\n\t\t\n<style>\n#text-1450175576 {\n  font-size: 0.75rem;\n  line-height: 1.75;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/en\/capabilities\" class=\"button white\"  >\n\t\t<span>Explore More<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-694815492 {\n  width: 72%;\n}\n#text-box-694815492 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1311723773 {\n  padding-top: 483px;\n}\n#banner-1311723773 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n#banner-1311723773 .banner-bg img {\n  object-position: 47% 46%;\n}\n@media (min-width:550px) {\n  #banner-1311723773 {\n    padding-top: 600px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\n  <div class=\"banner has-hover sticky-section hide-for-medium\" id=\"banner-778429881\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"693\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/ourteam.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-704719930\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-1050525946\" class=\"text\">\n\t\t\n<div class=\"\">\n<div class=\"sec8content\">\n<div>\n<h1>+370 Regional Employees<\/h1>\n<\/div>\n<\/div>\n<\/div>\n\t\t\n<style>\n#text-1050525946 {\n  line-height: 2.25;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/en\/our-people\" class=\"button white\"  >\n\t\t<span>Explore More<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-704719930 {\n  width: 72%;\n}\n#text-box-704719930 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-778429881 {\n  padding-top: 416px;\n}\n#banner-778429881 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n#banner-778429881 .banner-bg img {\n  object-position: 47% 46%;\n}\n<\/style>\n  <\/div>\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-17","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":238,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages\/17\/revisions"}],"predecessor-version":[{"id":1128,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages\/17\/revisions\/1128"}],"wp:attachment":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/media?parent=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}