{"id":533,"date":"2020-11-04T11:33:29","date_gmt":"2020-11-04T11:33:29","guid":{"rendered":"https:\/\/unipalgt.demo.oyounmedia.com\/?page_id=533"},"modified":"2020-12-16T13:05:52","modified_gmt":"2020-12-16T13:05:52","slug":"mission","status":"publish","type":"page","link":"https:\/\/unipalgt.com\/en\/mission","title":{"rendered":"Mission &#038; Values"},"content":{"rendered":"\n<h2 class=\"has-text-align-center wp-block-heading\">Our Mission<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Our mission is to continue being the number one added value full-service FMCG distributor in Palestine and beyond.<\/p>\n\n\n\n<p>Our goal is to distribute high quality branded FMCG products to every household via operating best in class GTM practices, for which trade and consumers will reward us with leading sales and profits.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Our Values<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"accordion\">\n\n\t<div id=\"accordion-1196559174\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1196559174-label\" class=\"accordion-title plain active\" href=\"#accordion-item-leadership\" aria-expanded=\"true\" aria-controls=\"accordion-1196559174-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Leadership<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1196559174-content\" class=\"accordion-inner\" style=\"display: block;\" aria-labelledby=\"accordion-1196559174-label\" >\n\t\t\t\n\n<ul>\n<li>Unipal is driven by a passion for winning<\/li>\n<li>Unipal\u2019s power lays in its agility<\/li>\n<li>Unipal\u2019s size and operations affects the whole local economic cycle<\/li>\n<li>Unipal is the leader in market practices innovations<\/li>\n<li>Unipal never compromises quality in its services and its products<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n<div class=\"accordion\">\n\n\t<div id=\"accordion-691694925\" class=\"accordion-item\">\n\t\t<a id=\"accordion-691694925-label\" class=\"accordion-title plain active\" href=\"#accordion-item-ethics\" aria-expanded=\"true\" aria-controls=\"accordion-691694925-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Ethics<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-691694925-content\" class=\"accordion-inner\" style=\"display: block;\" aria-labelledby=\"accordion-691694925-label\" >\n\t\t\t\n\n<ul>\n<li>Unipal claims full ownership &amp; accountability to meet business needs<\/li>\n<li>Unipal value transparency which is the cornerstone of its trustworthiness<\/li>\n<li>Unipal is proud of its openness &amp; integrity in all business functions and with all the stakeholders<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n<div class=\"accordion\">\n\n\t<div id=\"accordion-653068465\" class=\"accordion-item\">\n\t\t<a id=\"accordion-653068465-label\" class=\"accordion-title plain active\" href=\"#accordion-item-people\" aria-expanded=\"true\" aria-controls=\"accordion-653068465-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>People<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-653068465-content\" class=\"accordion-inner\" style=\"display: block;\" aria-labelledby=\"accordion-653068465-label\" >\n\t\t\t\n\n<ul>\n<li>Unipal recognizes the value of people in business growth and continuity<\/li>\n<li>Unipal recruits the best in class employees and provides long term careers<\/li>\n<li>Unipal provides its external stakeholders with business development opportunities<\/li>\n<li>Unipal thrives on long term relationships with suppliers, customers ,and employees<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Our Mission Our mission is to continue being the number one added value full-service FMCG distributor in Palestine and beyond. Our goal is to distribute high quality branded FMCG products to every household via operating best in class GTM practices, for which trade and consumers will reward us with leading sales and profits. Our Values<\/p>\n","protected":false},"author":3,"featured_media":506,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank-title-center.php","meta":{"footnotes":""},"class_list":["post-533","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages\/533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/comments?post=533"}],"version-history":[{"count":13,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages\/533\/revisions"}],"predecessor-version":[{"id":819,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages\/533\/revisions\/819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/media\/506"}],"wp:attachment":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/media?parent=533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}