{"id":559,"date":"2020-11-04T12:15:14","date_gmt":"2020-11-04T12:15:14","guid":{"rendered":"https:\/\/unipalgt.demo.oyounmedia.com\/?page_id=559"},"modified":"2025-12-05T10:41:23","modified_gmt":"2025-12-05T10:41:23","slug":"our-brands","status":"publish","type":"page","link":"https:\/\/unipalgt.com\/en\/our-brands","title":{"rendered":"Our Brands"},"content":{"rendered":"<div class=\"row align-equal row-box-shadow-1-hover\"  id=\"row-1765668225\">\n\n\t<div id=\"col-2021620057\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.pmi.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/philip_morris.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2022141654\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.ooredoo.ps\/en\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/ooredoo2.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-256472989\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/us.pg.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/pg.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1830773890\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.ferrero.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/ferrero.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-594590742\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 282.81962025316px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.mars.com\/made-by-mars\/mars-wrigley\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image__12_-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1632348463\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 130.6993006993px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.facebook.com\/XLPalestine\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/12\/XL_LOGO_new.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2068564849\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 384.63909774436px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.kelloggs.com\/en_US\/home.html\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Screenshot_2025-11-10_at_16.27.07-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-864552301\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 193.86734693878px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.reema.ps\/en\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/logo-2.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1541705292\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 232px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Screenshot_2025-11-10_at_16.22.41-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1585168071\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.siniorafood.com\/en-us\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/siniora.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-108550585\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 240.75722543353px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.kraftheinzcompany.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Screenshot_2025-11-16_at_14.42.13-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1689216555\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.55555555556px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.lotusbiscoff.com\/en-us\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image-5.jpeg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-70348581\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/americana.brightcreations.com\/who-we-are\/#:~:text=Americana%20Foods%3A,and%20cakes%2C%20chips%20and%20snacks.\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/americana.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1106464911\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 131px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/nadec.com\/en\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2023\/03\/Nadec-logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1401170562\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 380.29756097561px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.lotusbiscoff.com\/en-us\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Screenshot_2025-11-10_at_16.25.00-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-430604157\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.duracell.com\/en-us\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/duracell.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1238998253\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.givenchy.com\/us\/en-US\/homepage\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/givenchy.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1001868601\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.dior.com\/en_int\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/Dior.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-718473799\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.wella.com\/professional\/en-EN\/hair-color\/koleston-perfect\/koleston-perfect#\/?_k=2vr2ak\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/wella.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2094204152\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.scjohnson.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/scjohnson.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1500192276\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/ps.iqos.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/iqos.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-600328401\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.ariel-info.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/arial.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2086845135\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/us.pg.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/tide.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-116012740\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 173.28358208955px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.facebook.com\/girlscan.palestine\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/always.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1235413830\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.pampers.com\/en-us\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/pampers.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1117852408\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.headandshoulders.com\/en-us\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/head_shoulders.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2054094762\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/pantene.com\/en-us\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/pantene.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-757583488\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.facebook.com\/TheFairyArabia\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/fairy.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-500956403\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.gillettearabia.com\/ar-sa\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/gillette2.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1228359117\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.oralbarabia.com\/ar-sa\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/oralb.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1565458309\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.376px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image__13_-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1216603176\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 135.76024590164px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image__6_-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1068224020\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.376px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image__7_-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-204511131\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 210.1256684492px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image__8_-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1738876337\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.ferrerorocher.com\/int\/en\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/ferrero_rocher.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1171504003\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.nutella.com\/me\/ar\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/nutella.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2142366921\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.kinder.com\/me\/en\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/kinder.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-517153265\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.facebook.com\/RaffaelloMiddleEast\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/raffaello.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2125876734\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.376px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Tic_Tac_logo_and_symbol__meaning__history__PNG-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1495398728\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.orbitgum.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/Orbit.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-311935514\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.376px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/M_M_s_Logo__symbol__meaning__history__PNG__brand-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-672527150\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 131px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Snickers_Vector_Logo_-_Download_Free_SVG_Icon___Worldvectorlogo-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1638156124\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 209.376px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Mars_Logo_and_symbol__meaning__history__PNG__brand-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-586765337\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 167.15340909091px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Twix_logo_transparent_PNG_-_StickPNG-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-401401500\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 298.21576763485px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/File_Galaxy_chocolate_brand_logo-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-126859437\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 286.86851211073px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image__11_-removebg-preview.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-613968140\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 131px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.pringles.com\/us\/home.html\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/Pringles-Logo-PNG-Vector-AI-Free-Download.jpeg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1214093666\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 131px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image-9.jpeg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-689797635\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 131px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image-10.jpeg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1299731643\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 193.86734693878px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.reema.ps\/en\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/8c92056c652a0c2df7e07d964a6f983f-1.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1415405181\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 193.86734693878px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.reema.ps\/en\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/d35a042a32f148e7d8fe989bf2c2b2e6.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1084278432\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 240.78260869565px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.reema.ps\/en\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/502f2c430dba751b603b5df5977e9d43.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1959473199\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 193.86734693878px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.reema.ps\/en\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/df1b8647e6991ba7c381fdef57676ac4.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-511173369\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 193.86734693878px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.reema.ps\/en\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/6e64a466c99c0f93383d9c6b02e38b3d.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-450437286\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 131px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"#\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2025\/11\/image-12.jpeg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1501258153\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.raid.com\/en-us\/products\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/raid.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-511093213\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.pledge.com\/en-us\/products\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/Pledge.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1491450934\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.glade.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/glage.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-156045488\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.duck.co.uk\/en-gb\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/DUCK.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-696402665\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 174.71641791045px!important\"><a class=\"ux-logo-link block image-zoom\" title=\"\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.kiwicare.com\/\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"https:\/\/unipalgt.com\/en\/wp-content\/uploads\/2020\/11\/kiwi.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:101px;\" \/><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1874103159\" class=\"col medium-4 small-12 large-4\"  data-animate=\"BounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1765668225 > .col > .col-inner {\n  background-color: rgb(242, 242, 242);\n  border-radius: 12px;\n}\n<\/style>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":474,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank-title-center.php","meta":{"footnotes":""},"class_list":["post-559","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages\/559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/comments?post=559"}],"version-history":[{"count":64,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages\/559\/revisions"}],"predecessor-version":[{"id":1180,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/pages\/559\/revisions\/1180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/media\/474"}],"wp:attachment":[{"href":"https:\/\/unipalgt.com\/en\/wp-json\/wp\/v2\/media?parent=559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}